{"id":2683,"date":"2020-12-16T12:56:58","date_gmt":"2020-12-16T11:56:58","guid":{"rendered":"https:\/\/recetas.kuken.es\/?post_type=cp_recipe&#038;p=2683"},"modified":"2023-07-04T08:44:04","modified_gmt":"2023-07-04T06:44:04","slug":"pesto-sose","status":"publish","type":"cp_recipe","link":"https:\/\/recetas.kuken.es\/de\/rezept\/pesto-sose\/","title":{"rendered":"Pesto-Sauce"},"content":{"rendered":"<h2>Damit unser Pesto eine Qualit\u00e4tssauce ist, ist es wichtig, dass auch unsere Zutaten von Qualit\u00e4t sind. Verwenden Sie frische Pinienkerne, kleine Basilikumbl\u00e4tter und ein hochwertiges extra natives Oliven\u00f6l.<\/p>\n<p>Um ihn haltbar zu machen, bewahren Sie ihn am besten in einem Glasgef\u00e4\u00df im K\u00fchlschrank auf. Au\u00dferdem empfehlen wir, ihn mit einem L\u00f6ffel Oliven\u00f6l zu bedecken, bevor Sie den Deckel aufsetzen und ihn verschlie\u00dfen. <\/h2>\n<h3>Inhaltsstoffe<\/h3>\n<div class=\"cooked-recipe-ingredients\">\n<div class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"60\">60<\/span> <span class=\"cooked-ing-measurement\">grs<\/span> <span class=\"cooked-ing-name\">Basilikum <\/span><\/div>\n<div class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"60\">60<\/span> <span class=\"cooked-ing-measurement\">grs<\/span> <span class=\"cooked-ing-name\">von Pinienkernen <\/span><\/div>\n<div class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"60\">60<\/span> <span class=\"cooked-ing-measurement\">grs<\/span> <span class=\"cooked-ing-name\">Parmesank\u00e4se<\/span><\/div>\n<div class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"40\">40<\/span> <span class=\"cooked-ing-measurement\">grs<\/span> <span class=\"cooked-ing-name\">von ger\u00e4uchertem Schafsk\u00e4se <\/span><\/div>\n<div class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"1\">1<\/span> <span class=\"cooked-ing-measurement\"><\/span> <span class=\"cooked-ing-name\">Knoblauchzehe<\/span><\/div>\n<div class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"80\">80<\/span> <span class=\"cooked-ing-measurement\">ml<\/span> <span class=\"cooked-ing-name\">von Oliven\u00f6l <\/span><\/div>\n<div class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-name\">Salz<\/span><\/div>\n<div class=\"cooked-single-ingredient cooked-heading\">K\u00fcken Zubeh\u00f6r <\/div>\n<div class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-name\">Zubeh\u00f6r Klinge <\/span><\/div>\n<div class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-name\">Spatel <\/span><\/div>\n<\/div>\n<h3>Anweisungen<\/h3>\n<div class=\"cooked-recipe-directions\">\n<div class=\"cooked-single-direction cooked-heading\">Ausarbeitung<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Paso 1\">\n<div class=\"cooked-dir-content\">\n<p>R\u00f6sten Sie die Pinienkerne in einer Bratpfanne, bis sie leicht ger\u00f6stet sind. Beiseite legen.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Paso 2\">\n<div class=\"cooked-dir-content\">\n<p>Wir montieren das Messerzubeh\u00f6r an unseren K\u00fcken-Roboter.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Paso 3\">\n<div class=\"cooked-dir-content\">\n<p>F\u00fcgen Sie 60 g sauberes Basilikum ohne die z\u00e4hesten St\u00e4ngel, 60 g Parmesan und 40 g ger\u00e4ucherten Schafsk\u00e4se, beides in kleinen St\u00fccken, einen gesch\u00e4lten Knoblauch, die Pinienkerne und 80 ml Oliven\u00f6l hinzu.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Paso 4\">\n<div class=\"cooked-dir-content\">\n<p>Blenden Sie 1 Minute lang mit Stufe 5.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Paso 5\">\n<div class=\"cooked-dir-content\">\n<p>Nehmen Sie den Deckel ab und schieben Sie mit Hilfe des Spatels die Reste, die eventuell an der Wand des Glases geblieben sind, nach unten.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Paso 6\">\n<div class=\"cooked-dir-content\">\n<p>Schmecken Sie ab und passen Sie das Salz ggf. an.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Paso 7\">\n<div class=\"cooked-dir-content\">\n<p>Blenden Sie 10 Sekunden lang mit Stufe 5.<\/p>\n<\/div>\n<\/div>\n<\/div>","protected":false},"author":7,"featured_media":2684,"comment_status":"open","ping_status":"closed","template":"","recipe_category":[199],"class_list":["post-2683","cp_recipe","type-cp_recipe","status-publish","has-post-thumbnail","hentry","cp_recipe_category-salsas-e-ingredientes-base"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.0 (Yoast SEO v25.3.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Salsa pesto - Recetas K\u00fcken<\/title>\n<meta name=\"description\" content=\"Receta de salsa pesto tradicional. Aprende a prepararla paso a paso con el robot de cocina K\u00fcken TOUCH 9000.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recetas.kuken.es\/de\/rezept\/pesto-sose\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salsa pesto\" \/>\n<meta property=\"og:description\" content=\"Receta de salsa pesto tradicional. Aprende a prepararla paso a paso con el robot de cocina K\u00fcken TOUCH 9000.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recetas.kuken.es\/de\/rezept\/pesto-sose\/\" \/>\n<meta property=\"og:site_name\" content=\"Recetas K\u00fcken\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-04T06:44:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recetas.kuken.es\/wp-content\/uploads\/2020\/12\/salsa-pesto-tradicional.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"658\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/\",\"url\":\"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/\",\"name\":\"Salsa pesto - Recetas K\u00fcken\",\"isPartOf\":{\"@id\":\"https:\/\/recetas.kuken.es\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/recetas.kuken.es\/wp-content\/uploads\/2020\/12\/salsa-pesto-tradicional.jpg\",\"datePublished\":\"2020-12-16T11:56:58+00:00\",\"dateModified\":\"2023-07-04T06:44:04+00:00\",\"description\":\"Receta de salsa pesto tradicional. Aprende a prepararla paso a paso con el robot de cocina K\u00fcken TOUCH 9000.\",\"breadcrumb\":{\"@id\":\"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/#primaryimage\",\"url\":\"https:\/\/recetas.kuken.es\/wp-content\/uploads\/2020\/12\/salsa-pesto-tradicional.jpg\",\"contentUrl\":\"https:\/\/recetas.kuken.es\/wp-content\/uploads\/2020\/12\/salsa-pesto-tradicional.jpg\",\"width\":480,\"height\":658,\"caption\":\"Salsa pesto tradicional para platos de pasta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Recepten\",\"item\":\"https:\/\/recetas.kuken.es\/nl\/receptarchief\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salsa pesto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/recetas.kuken.es\/fr\/#website\",\"url\":\"https:\/\/recetas.kuken.es\/fr\/\",\"name\":\"Recetas K\u00fcken\",\"description\":\"Amplia variedad de recetas para tu robot de cocina\",\"publisher\":{\"@id\":\"https:\/\/recetas.kuken.es\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/recetas.kuken.es\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/recetas.kuken.es\/fr\/#organization\",\"name\":\"Alfa Dyser\",\"url\":\"https:\/\/recetas.kuken.es\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/recetas.kuken.es\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/recetas.kuken.es\/wp-content\/uploads\/2020\/11\/cropped-kuken-1.png\",\"contentUrl\":\"https:\/\/recetas.kuken.es\/wp-content\/uploads\/2020\/11\/cropped-kuken-1.png\",\"width\":377,\"height\":94,\"caption\":\"Alfa Dyser\"},\"image\":{\"@id\":\"https:\/\/recetas.kuken.es\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Salsa pesto - Recetas K\u00fcken","description":"Receta de salsa pesto tradicional. Aprende a prepararla paso a paso con el robot de cocina K\u00fcken TOUCH 9000.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recetas.kuken.es\/de\/rezept\/pesto-sose\/","og_locale":"de_DE","og_type":"article","og_title":"Salsa pesto","og_description":"Receta de salsa pesto tradicional. Aprende a prepararla paso a paso con el robot de cocina K\u00fcken TOUCH 9000.","og_url":"https:\/\/recetas.kuken.es\/de\/rezept\/pesto-sose\/","og_site_name":"Recetas K\u00fcken","article_modified_time":"2023-07-04T06:44:04+00:00","og_image":[{"width":480,"height":658,"url":"https:\/\/recetas.kuken.es\/wp-content\/uploads\/2020\/12\/salsa-pesto-tradicional.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/","url":"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/","name":"Salsa pesto - Recetas K\u00fcken","isPartOf":{"@id":"https:\/\/recetas.kuken.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/#primaryimage"},"image":{"@id":"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/#primaryimage"},"thumbnailUrl":"https:\/\/recetas.kuken.es\/wp-content\/uploads\/2020\/12\/salsa-pesto-tradicional.jpg","datePublished":"2020-12-16T11:56:58+00:00","dateModified":"2023-07-04T06:44:04+00:00","description":"Receta de salsa pesto tradicional. Aprende a prepararla paso a paso con el robot de cocina K\u00fcken TOUCH 9000.","breadcrumb":{"@id":"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/#primaryimage","url":"https:\/\/recetas.kuken.es\/wp-content\/uploads\/2020\/12\/salsa-pesto-tradicional.jpg","contentUrl":"https:\/\/recetas.kuken.es\/wp-content\/uploads\/2020\/12\/salsa-pesto-tradicional.jpg","width":480,"height":658,"caption":"Salsa pesto tradicional para platos de pasta"},{"@type":"BreadcrumbList","@id":"https:\/\/recetas.kuken.es\/receta\/salsa-pesto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Recepten","item":"https:\/\/recetas.kuken.es\/nl\/receptarchief\/"},{"@type":"ListItem","position":2,"name":"Salsa pesto"}]},{"@type":"WebSite","@id":"https:\/\/recetas.kuken.es\/fr\/#website","url":"https:\/\/recetas.kuken.es\/fr\/","name":"Recetas K\u00fcken","description":"Amplia variedad de recetas para tu robot de cocina","publisher":{"@id":"https:\/\/recetas.kuken.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recetas.kuken.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/recetas.kuken.es\/fr\/#organization","name":"Alfa Dyser","url":"https:\/\/recetas.kuken.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/recetas.kuken.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/recetas.kuken.es\/wp-content\/uploads\/2020\/11\/cropped-kuken-1.png","contentUrl":"https:\/\/recetas.kuken.es\/wp-content\/uploads\/2020\/11\/cropped-kuken-1.png","width":377,"height":94,"caption":"Alfa Dyser"},"image":{"@id":"https:\/\/recetas.kuken.es\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/recetas.kuken.es\/de\/wp-json\/wp\/v2\/cooked_recipe\/2683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recetas.kuken.es\/de\/wp-json\/wp\/v2\/cooked_recipe"}],"about":[{"href":"https:\/\/recetas.kuken.es\/de\/wp-json\/wp\/v2\/types\/cp_recipe"}],"author":[{"embeddable":true,"href":"https:\/\/recetas.kuken.es\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/recetas.kuken.es\/de\/wp-json\/wp\/v2\/comments?post=2683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recetas.kuken.es\/de\/wp-json\/wp\/v2\/media\/2684"}],"wp:attachment":[{"href":"https:\/\/recetas.kuken.es\/de\/wp-json\/wp\/v2\/media?parent=2683"}],"wp:term":[{"taxonomy":"cp_recipe_category","embeddable":true,"href":"https:\/\/recetas.kuken.es\/de\/wp-json\/wp\/v2\/recipe_category?post=2683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}